{"id":2192,"date":"2025-01-16T00:00:00","date_gmt":"2025-01-16T05:00:00","guid":{"rendered":"https:\/\/www.archspm.org\/406-audit-review-guidelines\/"},"modified":"2025-03-11T13:37:02","modified_gmt":"2025-03-11T17:37:02","slug":"406-audit-review-guidelines","status":"publish","type":"page","link":"https:\/\/www.archspm.org\/es\/policies\/400-finance\/406-audit-review-guidelines\/","title":{"rendered":"406 - Pol\u00edtica de auditor\u00eda, revisi\u00f3n y procedimientos acordados"},"content":{"rendered":"<h4 style=\"text-align: center;\">\u00daltima actualizaci\u00f3n: 3\/14\/2024<\/h4>\n<div class=\"policy_button_container\"><a href=\"https:\/\/archspmpolicies.s3.amazonaws.com\/400\/AUP%2BPolicy%2B406%2Bfinal%2B6-17-22.pdf\" target=\"_blank\" title=\"406 - Pol\u00edtica de auditor\u00eda, revisi\u00f3n y procedimientos acordados|target:_blank\" rel=\"noopener\">Descargar PDF<\/a><\/div>\n<div class=\"policy_button_container\"><a href=\"https:\/\/archspm1.sharepoint.com\/:b:\/s\/ResourceLibrary\/EWlVK83RTmlKoLitWGRdAFsB_MPLoDxldDnDzejx7cnrTw\" target=\"_blank\" title=\"P\u00e1gina complementaria de la Pol\u00edtica 406 - Pol\u00edtica de auditor\u00eda, revisi\u00f3n y procedimientos acordados|target:_blank\" rel=\"noopener\">Empresas AUP (P\u00e1gina suplementaria)<\/a><\/div>\n<h3 style=\"text-align: center;\">Archidi\u00f3cesis de Saint Paul y Minneapolis<\/h3>\n<h3 style=\"text-align: center;\">Pol\u00edtica de auditor\u00eda, revisi\u00f3n y procedimientos acordados<\/h3>\n<h3 style=\"text-align: center;\">Alcance: Todas las parroquias de la archidi\u00f3cesis<\/h3>\n<h3>I. Objetivo<\/h3>\n<p>Proporcionar los requisitos m\u00ednimos para los Procedimientos Acordados (AUP) en cada Parroquia para aquellas firmas de auditor\u00eda que deben completar el trabajo y las directrices en lo que se refiere a Auditor\u00edas, Revisiones y AUPs dentro de la Arquidi\u00f3cesis, lo que proporciona al P\u00e1rroco, a los Fideicomisarios y al Consejo Financiero Parroquial algunas garant\u00edas de que las finanzas de la Parroquia se est\u00e1n manejando adecuadamente.<\/p>\n<h3>II. Definiciones<\/h3>\n<p><strong>\"Procedimientos acordados (AUP)\"<\/strong> se entiende una revisi\u00f3n de los controles administrativos, financieros, contables y operativos, tal y como establece la Archidi\u00f3cesis de Saint Paul y Minneapolis.<\/p>\n<p><strong>\"Archidi\u00f3cesis\"<\/strong> significa cierta entidad corporativa formada, mantenida y existente bajo la Secci\u00f3n 315.16 de Minnesota con Nombre Comercial de Minnesota: \"La Archidi\u00f3cesis de St. Paul y Minneapolis\".<\/p>\n<p><strong>\"Auditor\u00eda\"<\/strong> significa un examen objetivo de los registros contables de una entidad, as\u00ed como la inspecci\u00f3n f\u00edsica de sus activos. Si lo realiza un contable p\u00fablico certificado (CPA), el CPA puede expresar una opini\u00f3n sobre la imparcialidad de los estados financieros de la entidad. Esta opini\u00f3n se emite entonces junto con los estados financieros para la comunidad inversora, bancaria u otra comunidad financiera SI SE REQUIERE.<\/p>\n<p><strong>\"Parroquia\"<\/strong> Se refiere a una parroquia dentro del territorio de la Archidi\u00f3cesis que es reconocida como cat\u00f3lica por la Archidi\u00f3cesis.<\/p>\n<p><strong>\"Consejo Parroquial de Finanzas\"<\/strong> significa el cuerpo consultivo can\u00f3nico establecido en una Parroquia de acuerdo con el canon 537 del C\u00f3digo de Derecho Can\u00f3nico de 1983 y la pol\u00edtica de la Archidi\u00f3cesis, que proporciona consulta al p\u00e1rroco de una muestra representativa de feligreses para compartir sus pensamientos y puntos de vista al servicio de la misi\u00f3n de una Parroquia espec\u00edfica.<\/p>\n<p><strong>\"Pastor\"<\/strong> se entiende un p\u00e1rroco o un administrador parroquial, seg\u00fan el caso.<\/p>\n<p><strong>\"Revisi\u00f3n\"<\/strong> significa una revisi\u00f3n de estados financieros y es un servicio en virtud del cual el contable obtiene una garant\u00eda limitada de que no hay modificaciones materiales que deban introducirse en los estados financieros de una entidad para que sean conformes con el marco de informaci\u00f3n financiera aplicable (como los PCGA). Una revisi\u00f3n no requiere que el contable obtenga una comprensi\u00f3n del control interno, ni que eval\u00fae el riesgo de fraude u otros tipos de procedimientos de auditor\u00eda. En consecuencia, una revisi\u00f3n no proporciona al contable la garant\u00eda de que ha tenido conocimiento de todas las cuestiones significativas que normalmente se habr\u00edan descubierto y revelado en una auditor\u00eda.<\/p>\n<p><strong>\"Fideicomisarios\"<\/strong> significa los dos miembros laicos de la Parroquia nombrados para servir como miembros y oficiales de la corporaci\u00f3n Parroquial por el Arzobispo, el Vicario General y el p\u00e1rroco o una mayor\u00eda de ellos.<\/p>\n<h3>III. Pol\u00edtica<\/h3>\n<p>1. Cada Parroquia debe tener un AUP realizado un m\u00ednimo de una vez cada tres a\u00f1os. Este requisito entrar\u00e1 en vigor para las Parroquias a m\u00e1s tardar el 30 de junio de 2022. Antes de que las Parroquias adopten el requisito de tres a\u00f1os, la Parroquia debe seguir cumpliendo con el requisito anterior de cinco a\u00f1os para una AUP.<\/p>\n<p>2. Cuando se produce un cambio de p\u00e1rroco, el nuevo p\u00e1rroco tiene derecho a exigir una auditor\u00eda, revisi\u00f3n o PUA para el per\u00edodo anterior al cambio de p\u00e1rroco, aunque no hayan transcurrido tres a\u00f1os desde la \u00faltima PUA.<\/p>\n<p>3. Si el nuevo P\u00e1rroco opta por renunciar a su derecho a una Auditor\u00eda, Revisi\u00f3n o AUP, la Parroquia deber\u00e1 recibir por escrito una exenci\u00f3n del Director Financiero de la Archidi\u00f3cesis.<\/p>\n<p>4. Una vez publicada, la Parroquia debe enviar una copia de la Auditor\u00eda, Revisi\u00f3n o AUP completada y de la carta de gesti\u00f3n al Director Financiero de la Archidi\u00f3cesis.<\/p>\n<p>5. Todos los informes de Auditor\u00eda, Revisi\u00f3n y AUP deben ser distribuidos, revisados y discutidos en una reuni\u00f3n del Consejo Financiero Parroquial preferiblemente por la empresa que complet\u00f3 el informe en una reuni\u00f3n a la que asistan el P\u00e1rroco, los Fideicomisarios y el Administrador de Negocios de la Parroquia (o cargo equivalente). Los cambios recomendados a los controles internos deben ser compartidos en esa reuni\u00f3n.<\/p>\n<p>6. Una Auditor\u00eda o Revisi\u00f3n independiente puede ser requerida por la instituci\u00f3n financiera de la Parroquia, agencia que otorga subvenciones, u otra. Adem\u00e1s, el P\u00e1rroco, a su discreci\u00f3n, puede requerir que se complete una Auditor\u00eda, Revisi\u00f3n o AUP en cualquier momento.<\/p>\n<p>7. El <a href=\"https:\/\/archspm1.sharepoint.com\/:b:\/s\/ResourceLibrary\/EWlVK83RTmlKoLitWGRdAFsB_MPLoDxldDnDzejx7cnrTw\" target=\"_blank\" rel=\"noopener\">empresas en el calendario adjunto<\/a> est\u00e1n aprobadas para completar una AUP para Parroquias. El calendario de empresas aprobadas puede ser modificado por el Director Financiero de la Archidi\u00f3cesis.<\/p>\n<p>8. Si la Parroquia encarga la realizaci\u00f3n de una Auditor\u00eda o Revisi\u00f3n, adem\u00e1s de la AUP, la Parroquia puede seleccionar una empresa distinta de las tres que figuran en el calendario adjunto. No obstante, la Parroquia deber\u00e1 ponerse en contacto con varias empresas que se encuentren en su zona geogr\u00e1fica. Es importante tener en cuenta los posibles conflictos de intereses que puedan surgir, como por ejemplo que los CPA asistan a la Parroquia o que sean miembros de un comit\u00e9 dentro de la Parroquia. Se recomienda pedir ofertas y entrevistar a dos o tres empresas, con la condici\u00f3n de que sean independientes y tengan experiencia en la contabilidad de fondos. El personal de la parroquia y los miembros del Consejo Parroquial de Finanzas deber\u00edan entrevistar a las empresas. Hay tres empresas de CPA aprobadas que apoyan el programa AUP y se enumeran en la lista adjunta. Si la parroquia elige a una empresa que no sea una de las empresas aprobadas para realizar una auditor\u00eda o revisi\u00f3n, la parroquia estar\u00e1 obligada a que una de las tres empresas aprobadas realice la AUP.<\/p>","protected":false},"excerpt":{"rendered":"<p>Last Updated: 3\/14\/2024 PDF Download AUP Firms (Supplemental Page) Archdiocese of Saint Paul and Minneapolis Audit, Review, and Agreed Upon Procedure Policy Scope: All Parishes in the Archdiocese I. Purpose To provide the minimum requirements for Agreed Upon Procedures (AUP) at each Parish for those audit firms whom must complete the work and guidelines as [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":2186,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2192","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/pages\/2192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/comments?post=2192"}],"version-history":[{"count":0,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/pages\/2192\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/pages\/2186"}],"wp:attachment":[{"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/media?parent=2192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}