{"id":4025,"date":"2020-05-01T22:16:22","date_gmt":"2020-05-02T02:16:22","guid":{"rendered":"https:\/\/www.archspm.org\/letter-from-archbishop-hebda-to-faithful-following-extension-of-governors-stay-at-home-order\/"},"modified":"2020-05-01T22:16:22","modified_gmt":"2020-05-02T02:16:22","slug":"letter-from-archbishop-hebda-to-faithful-following-extension-of-governors-stay-at-home-order","status":"publish","type":"post","link":"https:\/\/www.archspm.org\/es\/letter-from-archbishop-hebda-to-faithful-following-extension-of-governors-stay-at-home-order\/","title":{"rendered":"Carta del arzobispo Hebda a los fieles tras la pr\u00f3rroga de la orden de confinamiento del gobernador"},"content":{"rendered":"<p>Queridas hermanas y hermanos en Cristo<\/p>\n<p>Les sigo agradeciendo su compromiso, incluso en estos d\u00edas dif\u00edciles, por dar un alegre testimonio de la resurrecci\u00f3n de Jes\u00fas. Aprecio profundamente los sacrificios que han estado haciendo para que nosotros, como comunidad cat\u00f3lica, podamos dar un testimonio concreto de nuestro respeto por la vida humana y velar por el bienestar f\u00edsico y espiritual de nuestros hermanos y hermanas.<\/p>\n<p>Dada la pr\u00f3rroga de la orden de confinamiento del gobernador Walz hasta el 18 de mayo, la celebraci\u00f3n p\u00fablica de la misa en la Arquidi\u00f3cesis de Saint Paul y Minneapolis seguir\u00e1 suspendida hasta esa fecha.<\/p>\n<p>Los obispos de Minnesota se reunieron ayer, tras la conferencia de prensa del gobernador, para analizar detenidamente nuestro propio plan gradual de reanudaci\u00f3n de las misas p\u00fablicas. Somos conscientes de que, cuando volvamos a celebrar misas p\u00fablicas, tendremos que hacerlo siguiendo protocolos cuidadosamente definidos para garantizar la seguridad de las personas y evitar la propagaci\u00f3n del virus. Sabemos que, si trabajamos juntos, podremos hacerlo de manera segura.<\/p>\n<p>Debemos empezar ya a trabajar con nuestros sacerdotes y l\u00edderes parroquiales para estar preparados para celebrar algunas misas p\u00fablicas con aforo limitado a partir del 18 de mayo. Estamos elaborando un plan gradual, dividido en varias fases, para la reanudaci\u00f3n del culto p\u00fablico. En estos momentos nos encontramos en la fase uno. La fase dos nos permitir\u00e1 comenzar a celebrar algunas misas p\u00fablicas, y la fase tres nos permitir\u00e1 tener reuniones m\u00e1s grandes. Estas fases nos permitir\u00e1n reevaluar el proceso seg\u00fan sea necesario para garantizar la salud y la seguridad de la comunidad en el futuro. Nuestro plan supone que, en todo el estado, la dispensa de la obligaci\u00f3n de asistir a misa los domingos y d\u00edas de precepto continuar\u00e1 hasta que sea seguro para todos regresar.<\/p>\n<p>Todas las fases de este plan exigen el cumplimiento de estrictas normas de distanciamiento social y desinfecci\u00f3n.<\/p>\n<ul>\n<li>Se recomienda encarecidamente a las personas mayores de 65 a\u00f1os que no asistan, y cualquier persona que presente s\u00edntomas de enfermedad, o que tenga alg\u00fan miembro de su hogar enfermo o con s\u00edntomas de enfermedad, no debe acudir a la iglesia.<\/li>\n<li>El espacio de la iglesia se desinfectar\u00e1 a fondo antes y despu\u00e9s de cada servicio, incluyendo todas las entradas y puertas. Las pilas de agua bendita estar\u00e1n vac\u00edas y se retirar\u00e1n los himnarios.<\/li>\n<li>Se colocar\u00e1n carteles con informaci\u00f3n sobre las normas de distanciamiento social y de higiene, y se ofrecer\u00e1n recordatorios para que se cumplan dichas normas.<\/li>\n<li>Habr\u00e1 desinfectante de manos disponible en todas las entradas.<\/li>\n<li>Se cumplir\u00e1n todas las normas de seguridad locales relacionadas espec\u00edficamente con el uso adecuado de cubrebocas.<\/li>\n<li>Se pedir\u00e1 a las personas que eviten cualquier contacto f\u00edsico, como por ejemplo al saludarse.<\/li>\n<li>Las se\u00f1ales y otras instrucciones promover\u00e1n las pr\u00e1cticas de seguridad habituales necesarias para evitar el contagio (por ejemplo, toser o estornudar en la manga de la camisa, en un pa\u00f1uelo o en un pa\u00f1uelo de papel; evitar tocarse los ojos, la nariz y la boca).<\/li>\n<li>Se aumentar\u00e1 la ventilaci\u00f3n en la medida de lo posible abriendo ventanas y puertas, siempre que el clima lo permita.<\/li>\n<\/ul>\n<p>Mientras nos encontremos en la fase uno, nuestras iglesias pueden permanecer abiertas todos los d\u00edas para la oraci\u00f3n, y los sacerdotes pueden organizar la adoraci\u00f3n del Sant\u00edsimo Sacramento seg\u00fan sus posibilidades. Las confesiones pueden realizarse en espacios bien ventilados, respetando el distanciamiento social adecuado y garantizando al mismo tiempo la privacidad del sacramento. Muchas parroquias han celebrado confesiones al aire libre, lo cual puede funcionar bien. Tambi\u00e9n est\u00e1 permitido celebrar bodas o funerales con un m\u00e1ximo de 10 personas presentes. Tambi\u00e9n se permiten las misas al aire libre sin distribuci\u00f3n de la Sagrada Comuni\u00f3n, incluida la bendici\u00f3n en la que las personas permanecen en sus autom\u00f3viles, minimizando as\u00ed el peligro de propagaci\u00f3n de la infecci\u00f3n.<\/p>\n<p>Prevemos comenzar la fase dos el 18 de mayo. Trabajaremos en colaboraci\u00f3n con las autoridades p\u00fablicas para alcanzar ese objetivo. Durante la fase dos, se permitir\u00e1n misas p\u00fablicas en las iglesias en grupos m\u00e1s reducidos, limitados a no m\u00e1s de un tercio del aforo de la iglesia (aproximadamente cada 3<sup>rd<\/sup> (banco). Las parroquias deben respetar en todo momento las directrices vigentes en materia de distanciamiento social entre personas que no pertenezcan al mismo hogar.<\/p>\n<p>Las parroquias deber\u00e1n establecer medidas para garantizar que se respete estrictamente este l\u00edmite de aforo, por ejemplo, mediante la implementaci\u00f3n de inscripciones en l\u00ednea y la presencia de acomodadores que se aseguren de que las aglomeraciones se mantengan limitadas y controladas. Dado que se ha dispensado la obligaci\u00f3n dominical, se animar\u00e1 a los cat\u00f3licos a asistir a otras misas durante la semana en lugar de hacerlo el domingo, con el fin de distribuir el n\u00famero de asistentes. En algunos casos, ser\u00e1 necesario celebrar m\u00e1s misas de lo habitual para dar cabida a todas las personas que deseen asistir a misa durante esta fase.<\/p>\n<p>Tenemos la intenci\u00f3n de proporcionar protocolos detallados que deber\u00e1n seguirse para la celebraci\u00f3n de la misa y la distribuci\u00f3n de la Sagrada Comuni\u00f3n con suficiente antelaci\u00f3n a la fecha en que se reanuden las misas p\u00fablicas, de modo que las parroquias puedan prepararse para la forma prudente en que tendremos que avanzar. No se permitir\u00e1n las reuniones sociales ni otras reuniones de grupos peque\u00f1os durante la fase dos, ya que no cuentan con el mismo control de movimiento que la misa. Se podr\u00e1n permitir algunas otras celebraciones sacramentales, pero nunca podr\u00e1n exceder el 1\/3 de la capacidad de asientos de la iglesia. Si una celebraci\u00f3n o evento lit\u00fargico no puede mantener la capacidad y otros requisitos de distanciamiento social, no podr\u00e1 llevarse a cabo durante esta fase.<\/p>\n<p>Por el momento, no sabemos cu\u00e1ndo podremos pasar a la fase tres, lo que nos dar\u00eda m\u00e1s oportunidades de celebrar eventos con mayor n\u00famero de personas. Seguiremos evaluando la situaci\u00f3n y siguiendo las recomendaciones de las autoridades civiles y los expertos en salud p\u00fablica.<\/p>\n<p>Por favor, sigan orando por nuestros hermanos y hermanas que han fallecido a causa del COVID-19, por quienes los lloran, por quienes padecen esta enfermedad y por las personas que los cuidan, a menudo poniendo en grave riesgo su propia vida y la de sus familias. Sepan que rezo por ellos, por ustedes y por sus seres queridos.<\/p>\n<p>Al comenzar este mes de mayo, os dedico mis oraciones a cada uno de vosotros por intercesi\u00f3n de nuestra Sant\u00edsima Madre, Consoladora de los afligidos, y quedo,<\/p>\n<p>Sinceramente en Cristo,<br \/>\nReverend\u00edsimo Bernard A. Hebda<br \/>\nArzobispo de San Pablo y Minneapolis<\/p>\n<p><a href=\"https:\/\/archspmmainsite.s3.amazonaws.com\/News\/COVID19\/COVID19+MASS+UPDATE+%2BHEBDA+5-1-20+FINAL.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la carta (PDF)<\/a><\/p>\n<p><a href=\"https:\/\/archspmmainsite.s3.amazonaws.com\/News\/COVID19\/Covid-19.MassUpdate.Hebda.SPA.Final+signature.docx\" target=\"_blank\" rel=\"noopener\">Descargar la carta en espa\u00f1ol (PDF)<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Del arzobispo Bernard A. Hebda: Sigo agradecido por su compromiso, incluso en estos d\u00edas dif\u00edciles, de dar testimonio gozoso de la resurrecci\u00f3n de Jes\u00fas.<\/p>","protected":false},"author":2,"featured_media":7112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[34],"class_list":["post-4025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-announcements","tag-covid19"],"_links":{"self":[{"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/posts\/4025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/comments?post=4025"}],"version-history":[{"count":0,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/posts\/4025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/media\/7112"}],"wp:attachment":[{"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/media?parent=4025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/categories?post=4025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archspm.org\/es\/wp-json\/wp\/v2\/tags?post=4025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}